{"id":88052,"date":"2024-07-24T12:42:49","date_gmt":"2024-07-24T16:42:49","guid":{"rendered":"https:\/\/yesmontreal.ca\/event\/business-bootcamp-launch-your-business-2025-07-03-2025-07-31\/?eventDate=2025-09-04"},"modified":"2026-02-12T11:05:42","modified_gmt":"2026-02-12T16:05:42","slug":"bootcamp-affaires-lancez-votre-parcours-entrepreneurial-2025-09-04","status":"publish","type":"tribe_events","link":"https:\/\/yesmontreal.ca\/fr\/event\/bootcamp-affaires-lancez-votre-parcours-entrepreneurial\/2025-09-04\/","title":{"rendered":"Bootcamp d\u2019affaires : Lancez votre parcours entrepreneurial"},"content":{"rendered":"<h1><img decoding=\"async\" class=\"alignnone wp-image-71025 size-large\" src=\"https:\/\/yesmontreal.ca\/wp-content\/uploads\/feb-newsletter-1024x500.jpg\" alt=\"jeunes entrepreneurs apprenant comment d\u00e9marrer une petite entreprise\" width=\"1024\" height=\"500\" \/><\/h1>\n<p>&nbsp;<\/p>\n<h1><strong>Bootcamp d\u2019affaires : Lancez votre parcours entrepreneurial<\/strong><\/h1>\n<p>&nbsp;<\/p>\n<h2><strong>Pr\u00eat\u00b7e \u00e0 transformer votre id\u00e9e d\u2019entreprise en r\u00e9alit\u00e9\u00a0?<\/strong><\/h2>\n<p>Notre <strong>bootcamp d\u2019affaires en 4 s\u00e9ances<\/strong> vous offre le coaching d\u2019experts et les outils pratiques dont vous avez besoin pour lancer votre entreprise et d\u00e9marrer votre parcours entrepreneurial avec confiance. Anim\u00e9 par des coachs chevronn\u00e9s, ce bootcamp interactif vous guidera pas \u00e0 pas pour affiner votre id\u00e9e, tester vos concepts et cr\u00e9er un plan d\u2019affaires solide.<\/p>\n<h2><\/h2>\n<h2><strong>Ce que vous allez apprendre et r\u00e9aliser<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p>\ud83c\udfa5 Regardez cette vid\u00e9o pour un aper\u00e7u de ce qui vous attend\u00a0!<\/p>\n<p>&nbsp;<\/p>\n<div style=\"width: 1080px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-88052-1\" width=\"1080\" height=\"1920\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/yesmontreal.ca\/wp-content\/uploads\/Business_Bootcamp_Expectations_Ready.mp4?_=1\" \/><a href=\"https:\/\/yesmontreal.ca\/wp-content\/uploads\/Business_Bootcamp_Expectations_Ready.mp4\">https:\/\/yesmontreal.ca\/wp-content\/uploads\/Business_Bootcamp_Expectations_Ready.mp4<\/a><\/video><\/div>\n<h3><\/h3>\n<h3><strong>Compl\u00e9ter votre Business Model Canvas<\/strong><\/h3>\n<p>Apprenez \u00e0 utiliser cet outil essentiel pour cartographier les composantes cl\u00e9s de votre entreprise, y compris les opportunit\u00e9s, les activit\u00e9s et les sources de revenus.<\/p>\n<h3><strong>Occasions de r\u00e9seautage<\/strong><\/h3>\n<p>D\u00e9veloppez votre r\u00e9seau professionnel en vous connectant avec des entrepreneur\u00b7e\u00b7s et des collaborateur\u00b7trice\u00b7s partageant les m\u00eames id\u00e9es.<\/p>\n<h3><strong>Pratique de pitch<\/strong><\/h3>\n<p>Peaufinez votre pitch d\u2019affaires devant un public bienveillant. Vous pourriez m\u00eame gagner un acc\u00e8s gratuit \u00e0 nos ateliers payants\u00a0!<\/p>\n<h3><strong>R\u00e9troaction personnalis\u00e9e<\/strong><\/h3>\n<p>Recevez une r\u00e9troaction d\u2019experts sur vos plans d\u2019affaires et vos pr\u00e9sentations de pitch pour vous aider \u00e0 progresser et r\u00e9ussir.<\/p>\n<h3><strong>\u00c9tapes concr\u00e8tes pour votre entreprise<\/strong><\/h3>\n<p>Repartez du bootcamp avec des \u00e9tapes claires et actionnables pour lancer et d\u00e9velopper votre entreprise. Pour \u00e9viter les erreurs courantes au d\u00e9marrage, consultez notre billet de blogue <strong><a href=\"https:\/\/yesmontreal.ca\/avoiding-common-startup-mistakes\/\" target=\"_new\" rel=\"noopener\">\u00c9viter les erreurs courantes au d\u00e9marrage<\/a><\/strong>.<\/p>\n<h3><strong>Ressources exclusives<\/strong><\/h3>\n<p>Acc\u00e9dez \u00e0 des outils et gabarits exclusifs aux participant\u00b7e\u00b7s du bootcamp, y compris une trousse compl\u00e8te de planification d\u2019affaires.<\/p>\n<h3><strong>Certification professionnelle<\/strong><\/h3>\n<p>Obtenez une attestation de r\u00e9ussite pour valoriser votre profil professionnel et d\u00e9montrer votre expertise entrepreneuriale.<\/p>\n<h3><strong>Soutien de suivi<\/strong><\/h3>\n<p>B\u00e9n\u00e9ficiez d\u2019un accompagnement continu, incluant une s\u00e9ance de coaching gratuite ou l\u2019acc\u00e8s \u00e0 des ateliers avanc\u00e9s apr\u00e8s le bootcamp.<\/p>\n<h2><\/h2>\n<h2><strong>Des s\u00e9ances engageantes et interactives<\/strong><\/h2>\n<h3><strong>Groupes de responsabilisation entre pairs<\/strong><\/h3>\n<p>Rejoignez des groupes de responsabilisation pour un soutien mutuel qui vous aide \u00e0 garder le cap tout au long de votre parcours.<\/p>\n<h3><strong>Ateliers pratiques et activit\u00e9s de groupe<\/strong><\/h3>\n<p>Participez \u00e0 des ateliers pratiques et \u00e0 des activit\u00e9s de groupe qui renforcent vos apprentissages et vos comp\u00e9tences d\u2019affaires.<\/p>\n<h2><\/h2>\n<h2><strong>Ne manquez pas cette occasion de propulser votre parcours entrepreneurial\u00a0!<\/strong><\/h2>\n<p>Que vous lanciez une <strong>entreprise de produits<\/strong> ou une <strong>entreprise de services<\/strong>, ce bootcamp vous donne les outils et les connaissances pour r\u00e9ussir sur un march\u00e9 comp\u00e9titif. Apprenez \u00e0 cr\u00e9er un mod\u00e8le d\u2019affaires gagnant, \u00e0 tester vos id\u00e9es et \u00e0 communiquer votre proposition de valeur.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Dates du bootcamp<\/strong><\/h2>\n<p><strong>S\u00e9rie 1, les jeudis 15, 22, 29 janvier et 5 f\u00e9vrier 2026, de 18 h \u00e0 20 h 30<\/strong><\/p>\n<p><strong>S\u00e9rie 2, les jeudis 5, 12, 19 et 26 f\u00e9vrier 2026, de 13 h \u00e0 15 h 30<\/strong><\/p>\n<p><strong>S\u00e9rie 3, les jeudis 5, 12, 19 et 26 mars 2026, de 18 h \u00e0 20 h 30<\/strong><\/p>\n<p><strong>S\u00e9rie 4, les jeudis 2, 9, 16 et 23 avril 2026, de 13 h \u00e0 15 h 30<\/strong><\/p>\n<p><strong>S\u00e9rie 5, les jeudis 4, 11, 18 et 25 juin 2026, de 13 h \u00e0 15 h 30<\/strong><\/p>\n<p><strong>S\u00e9rie 6, les jeudis 2, 9, 16 et 23 juillet 2026, de 13 h \u00e0 15 h 30<\/strong><\/p>\n<p><strong>S\u00e9rie 7, les jeudis 30 juillet, 6, 13 et 20 ao\u00fbt 2026, de 13 h \u00e0 15 h 30<\/strong><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Comment s\u2019inscrire<\/strong><\/h2>\n<p>Pour plus d\u2019informations et pour vous inscrire, t\u00e9l\u00e9phonez au <strong>438-812-0168<\/strong>\u00a0ou \u00e9crivez \u00e0 <a href=\"mailto:servicescoordinator@yesmontreal.ca\" target=\"_blank\" rel=\"noopener\"><strong>servicescoordinator@yesmontreal.ca<\/strong><\/a>.<\/p>\n<p><strong>Note<\/strong>\u00a0: Les participant\u00b7e\u00b7s doivent avoir un dossier actif chez YES pour s\u2019inscrire et suivre la s\u00e9rie dans l\u2019ordre. Si vous manquez une s\u00e9ance, vous devrez attendre la prochaine cohorte pour poursuivre.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Adh\u00e9rez \u00e0 notre programme d\u2019entrepreneuriat pour seulement 30\u00a0$ par ann\u00e9e<\/strong><\/h2>\n<p>Profitez d\u2019un an d\u2019avantages, dont du coaching individuel gratuit, des bootcamps d\u2019affaires, des ressources juridiques et des cliniques de comptabilit\u00e9.<\/p>\n<p>Pour en savoir plus sur nos services pour entrepreneur\u00b7e\u00b7s, cliquez <strong><a href=\"https:\/\/yesmontreal.ca\/fr\/entrepreneuriat\/\" target=\"_blank\" rel=\"noopener\">ici<\/a><\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bootcamp d\u2019affaires en 4 s\u00e9ances : coaching d\u2019experts, mod\u00e8le d\u2019affaires, pitch, ressources et suivi. Cohortes d\u00e8s septembre 2025.<\/p>\n","protected":false},"author":10,"featured_media":0,"template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[272,273,274,275,276,277,324,279,280],"tribe_events_cat":[281,283],"class_list":["post-88052","tribe_events","type-tribe_events","status-publish","hentry","tag-business-regulations-fr","tag-business-skills-fr","tag-business-tools-fr","tag-entrepreneurs-fr","tag-entrepreneurship-fr","tag-entrepreneurship-training-fr","tag-entreprises","tag-small-business-fr","tag-starting-a-business-fr","tribe_events_cat-daytime-fr","tribe_events_cat-entrepreneurship-fr","cat_daytime-fr","cat_entrepreneurship-fr","tribe-recurring-event","tribe-recurring-event-child"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bootcamp d\u2019affaires : Lancez votre parcours entrepreneurial<\/title>\n<meta name=\"description\" content=\"Bootcamp d\u2019affaires en 4 s\u00e9ances : coaching d\u2019experts, mod\u00e8le d\u2019affaires, pitch, ressources et suivi. Cohortes d\u00e8s septembre 2025.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/yesmontreal.ca\/fr\/event\/bootcamp-affaires-lancez-votre-parcours-entrepreneurial\/2025-09-04\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bootcamp d\u2019affaires : Lancez votre parcours entrepreneurial\" \/>\n<meta property=\"og:description\" content=\"Bootcamp d\u2019affaires en 4 s\u00e9ances : coaching d\u2019experts, mod\u00e8le d\u2019affaires, pitch, ressources et suivi. Cohortes d\u00e8s septembre 2025.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/yesmontreal.ca\/fr\/event\/bootcamp-affaires-lancez-votre-parcours-entrepreneurial\/2025-09-04\/\" \/>\n<meta property=\"og:site_name\" content=\"YES Employment and Entrepreneurship\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/yes.montreal\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-12T16:05:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/yesmontreal.ca\/wp-content\/uploads\/feb-newsletter.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1189\" \/>\n\t<meta property=\"og:image:height\" content=\"580\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@YESMontreal\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/yesmontreal.ca\\\/fr\\\/event\\\/bootcamp-affaires-lancez-votre-parcours-entrepreneurial\\\/2025-09-04\\\/\",\"url\":\"https:\\\/\\\/yesmontreal.ca\\\/fr\\\/event\\\/bootcamp-affaires-lancez-votre-parcours-entrepreneurial\\\/2025-09-04\\\/\",\"name\":\"Bootcamp d\u2019affaires : Lancez votre parcours entrepreneurial\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/yesmontreal.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/yesmontreal.ca\\\/fr\\\/event\\\/bootcamp-affaires-lancez-votre-parcours-entrepreneurial\\\/2025-09-04\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/yesmontreal.ca\\\/fr\\\/event\\\/bootcamp-affaires-lancez-votre-parcours-entrepreneurial\\\/2025-09-04\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/yesmontreal.ca\\\/wp-content\\\/uploads\\\/feb-newsletter-1024x500.jpg\",\"datePublished\":\"2024-07-24T16:42:49+00:00\",\"dateModified\":\"2026-02-12T16:05:42+00:00\",\"description\":\"Bootcamp d\u2019affaires en 4 s\u00e9ances : coaching d\u2019experts, mod\u00e8le d\u2019affaires, pitch, ressources et suivi. Cohortes d\u00e8s septembre 2025.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/yesmontreal.ca\\\/fr\\\/event\\\/bootcamp-affaires-lancez-votre-parcours-entrepreneurial\\\/2025-09-04\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/yesmontreal.ca\\\/fr\\\/event\\\/bootcamp-affaires-lancez-votre-parcours-entrepreneurial\\\/2025-09-04\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/yesmontreal.ca\\\/fr\\\/event\\\/bootcamp-affaires-lancez-votre-parcours-entrepreneurial\\\/2025-09-04\\\/#primaryimage\",\"url\":\"https:\\\/\\\/yesmontreal.ca\\\/wp-content\\\/uploads\\\/feb-newsletter-1024x500.jpg\",\"contentUrl\":\"https:\\\/\\\/yesmontreal.ca\\\/wp-content\\\/uploads\\\/feb-newsletter-1024x500.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/yesmontreal.ca\\\/fr\\\/event\\\/bootcamp-affaires-lancez-votre-parcours-entrepreneurial\\\/2025-09-04\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/yesmontreal.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/yesmontreal.ca\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bootcamp d\u2019affaires : Lancez votre parcours entrepreneurial\",\"item\":\"https:\\\/\\\/yesmontreal.ca\\\/fr\\\/event\\\/bootcamp-affaires-lancez-votre-parcours-entrepreneurial\\\/2025-07-31\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Bootcamp d\u2019affaires : Lancez votre parcours entrepreneurial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/yesmontreal.ca\\\/#website\",\"url\":\"https:\\\/\\\/yesmontreal.ca\\\/\",\"name\":\"YES Employment and Entrepreneurship\",\"description\":\"Free Employment and Entrepreneurship services in Quebec\",\"publisher\":{\"@id\":\"https:\\\/\\\/yesmontreal.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/yesmontreal.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/yesmontreal.ca\\\/#organization\",\"name\":\"YES Employment + Entrepreneurship\",\"alternateName\":\"YES Montreal\",\"url\":\"https:\\\/\\\/yesmontreal.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/yesmontreal.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/yesmontreal.ca\\\/wp-content\\\/uploads\\\/Screen-Shot-2021-03-04-at-2.59.30-PM.png\",\"contentUrl\":\"https:\\\/\\\/yesmontreal.ca\\\/wp-content\\\/uploads\\\/Screen-Shot-2021-03-04-at-2.59.30-PM.png\",\"width\":636,\"height\":308,\"caption\":\"YES Employment + Entrepreneurship\"},\"image\":{\"@id\":\"https:\\\/\\\/yesmontreal.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/yes.montreal\",\"https:\\\/\\\/x.com\\\/YESMontreal\",\"https:\\\/\\\/www.instagram.com\\\/yesmontreal\\\/\",\"http:\\\/\\\/ca.linkedin.com\\\/in\\\/yesmontreal\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/YESMontreal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bootcamp d\u2019affaires : Lancez votre parcours entrepreneurial","description":"Bootcamp d\u2019affaires en 4 s\u00e9ances : coaching d\u2019experts, mod\u00e8le d\u2019affaires, pitch, ressources et suivi. Cohortes d\u00e8s septembre 2025.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/yesmontreal.ca\/fr\/event\/bootcamp-affaires-lancez-votre-parcours-entrepreneurial\/2025-09-04\/","og_locale":"fr_FR","og_type":"article","og_title":"Bootcamp d\u2019affaires : Lancez votre parcours entrepreneurial","og_description":"Bootcamp d\u2019affaires en 4 s\u00e9ances : coaching d\u2019experts, mod\u00e8le d\u2019affaires, pitch, ressources et suivi. Cohortes d\u00e8s septembre 2025.","og_url":"https:\/\/yesmontreal.ca\/fr\/event\/bootcamp-affaires-lancez-votre-parcours-entrepreneurial\/2025-09-04\/","og_site_name":"YES Employment and Entrepreneurship","article_publisher":"https:\/\/www.facebook.com\/yes.montreal","article_modified_time":"2026-02-12T16:05:42+00:00","og_image":[{"width":1189,"height":580,"url":"https:\/\/yesmontreal.ca\/wp-content\/uploads\/feb-newsletter.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@YESMontreal","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/yesmontreal.ca\/fr\/event\/bootcamp-affaires-lancez-votre-parcours-entrepreneurial\/2025-09-04\/","url":"https:\/\/yesmontreal.ca\/fr\/event\/bootcamp-affaires-lancez-votre-parcours-entrepreneurial\/2025-09-04\/","name":"Bootcamp d\u2019affaires : Lancez votre parcours entrepreneurial","isPartOf":{"@id":"https:\/\/yesmontreal.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/yesmontreal.ca\/fr\/event\/bootcamp-affaires-lancez-votre-parcours-entrepreneurial\/2025-09-04\/#primaryimage"},"image":{"@id":"https:\/\/yesmontreal.ca\/fr\/event\/bootcamp-affaires-lancez-votre-parcours-entrepreneurial\/2025-09-04\/#primaryimage"},"thumbnailUrl":"https:\/\/yesmontreal.ca\/wp-content\/uploads\/feb-newsletter-1024x500.jpg","datePublished":"2024-07-24T16:42:49+00:00","dateModified":"2026-02-12T16:05:42+00:00","description":"Bootcamp d\u2019affaires en 4 s\u00e9ances : coaching d\u2019experts, mod\u00e8le d\u2019affaires, pitch, ressources et suivi. Cohortes d\u00e8s septembre 2025.","breadcrumb":{"@id":"https:\/\/yesmontreal.ca\/fr\/event\/bootcamp-affaires-lancez-votre-parcours-entrepreneurial\/2025-09-04\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/yesmontreal.ca\/fr\/event\/bootcamp-affaires-lancez-votre-parcours-entrepreneurial\/2025-09-04\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/yesmontreal.ca\/fr\/event\/bootcamp-affaires-lancez-votre-parcours-entrepreneurial\/2025-09-04\/#primaryimage","url":"https:\/\/yesmontreal.ca\/wp-content\/uploads\/feb-newsletter-1024x500.jpg","contentUrl":"https:\/\/yesmontreal.ca\/wp-content\/uploads\/feb-newsletter-1024x500.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/yesmontreal.ca\/fr\/event\/bootcamp-affaires-lancez-votre-parcours-entrepreneurial\/2025-09-04\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/yesmontreal.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/yesmontreal.ca\/events\/"},{"@type":"ListItem","position":3,"name":"Bootcamp d\u2019affaires : Lancez votre parcours entrepreneurial","item":"https:\/\/yesmontreal.ca\/fr\/event\/bootcamp-affaires-lancez-votre-parcours-entrepreneurial\/2025-07-31\/"},{"@type":"ListItem","position":4,"name":"Bootcamp d\u2019affaires : Lancez votre parcours entrepreneurial"}]},{"@type":"WebSite","@id":"https:\/\/yesmontreal.ca\/#website","url":"https:\/\/yesmontreal.ca\/","name":"YES Employment and Entrepreneurship","description":"Free Employment and Entrepreneurship services in Quebec","publisher":{"@id":"https:\/\/yesmontreal.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/yesmontreal.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/yesmontreal.ca\/#organization","name":"YES Employment + Entrepreneurship","alternateName":"YES Montreal","url":"https:\/\/yesmontreal.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/yesmontreal.ca\/#\/schema\/logo\/image\/","url":"https:\/\/yesmontreal.ca\/wp-content\/uploads\/Screen-Shot-2021-03-04-at-2.59.30-PM.png","contentUrl":"https:\/\/yesmontreal.ca\/wp-content\/uploads\/Screen-Shot-2021-03-04-at-2.59.30-PM.png","width":636,"height":308,"caption":"YES Employment + Entrepreneurship"},"image":{"@id":"https:\/\/yesmontreal.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/yes.montreal","https:\/\/x.com\/YESMontreal","https:\/\/www.instagram.com\/yesmontreal\/","http:\/\/ca.linkedin.com\/in\/yesmontreal","https:\/\/www.youtube.com\/user\/YESMontreal"]}]}},"_links":{"self":[{"href":"https:\/\/yesmontreal.ca\/fr\/wp-json\/wp\/v2\/tribe_events\/88052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yesmontreal.ca\/fr\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/yesmontreal.ca\/fr\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/yesmontreal.ca\/fr\/wp-json\/wp\/v2\/users\/10"}],"version-history":[{"count":0,"href":"https:\/\/yesmontreal.ca\/fr\/wp-json\/wp\/v2\/tribe_events\/88052\/revisions"}],"wp:attachment":[{"href":"https:\/\/yesmontreal.ca\/fr\/wp-json\/wp\/v2\/media?parent=88052"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/yesmontreal.ca\/fr\/wp-json\/wp\/v2\/tags?post=88052"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/yesmontreal.ca\/fr\/wp-json\/wp\/v2\/tribe_events_cat?post=88052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}