{"id":85348,"date":"2025-05-16T15:26:24","date_gmt":"2025-05-16T19:26:24","guid":{"rendered":"https:\/\/yesmontreal.ca\/event\/seances-dinformation-pour-les-demandeurs-demploi\/?eventDate=2025-05-22"},"modified":"2025-05-16T16:11:08","modified_gmt":"2025-05-16T20:11:08","slug":"seances-dinformation-pour-les-demandeurs-demploi-2025-05-22","status":"publish","type":"tribe_events","link":"https:\/\/yesmontreal.ca\/fr\/event\/seances-dinformation-pour-les-demandeurs-demploi\/2025-05-22\/","title":{"rendered":"S\u00e9ances d&rsquo;information pour les demandeurs d&#8217;emploi"},"content":{"rendered":"<h1><img decoding=\"async\" class=\"alignnone size-full wp-image-76853\" src=\"https:\/\/yesmontreal.ca\/wp-content\/uploads\/job-interview.jpg\" alt=\"obtenir des conseils d'experts en mati\u00e8re d'emploi\" width=\"940\" height=\"627\" \/><\/h1>\n<p>&nbsp;<\/p>\n<h1><strong>Obtenir des conseils d&rsquo;experts en mati\u00e8re de recherche d&#8217;emploi &#8211; S\u00e9ances d&rsquo;information gratuites pour les demandeurs d&#8217;emploi<\/strong><\/h1>\n<p>&nbsp;<\/p>\n<p><strong><em>*Veuillez noter que cet session sera pr\u00e9sent\u00e9 en anglais.<\/em><\/strong><\/p>\n<h2><strong>Vous avez des difficult\u00e9s dans votre recherche d&#8217;emploi ? Vous n&rsquo;\u00eates pas s\u00fbr des prochaines \u00e9tapes ? <\/strong><\/h2>\n<p data-start=\"59\" data-end=\"475\">Obtenez des conseils d&rsquo;experts en mati\u00e8re de recherche d&#8217;emploi Que vous mettiez \u00e0 jour votre <strong data-start=\"160\" data-end=\"166\">CV<\/strong> et ayez besoin de l&rsquo;avis d&rsquo;un expert, que vous ayez du mal \u00e0 r\u00e9diger une <strong data-start=\"215\" data-end=\"231\">lettre de motivation<\/strong> qui retienne l&rsquo;attention des employeurs ou que vous vous demandiez comment faire ressortir votre <strong data-start=\"295\" data-end=\"315\">profil LinkedIn<\/strong>, nous sommes l\u00e0 pour vous aider ! Nos <strong data-start=\"351\" data-end=\"392\">s\u00e9ances d&rsquo;information gratuites pour les demandeurs d&#8217;emploi<\/strong> offrent des conseils personnalis\u00e9s pour vous aider \u00e0 naviguer sur le march\u00e9 du travail en toute confiance.<\/p>\n<p data-start=\"477\" data-end=\"840\">Vous vous pr\u00e9parez peut-\u00eatre \u00e0 un <strong data-start=\"516\" data-end=\"533\">entretien d&#8217;embauche<\/strong> et souhaitez affiner vos r\u00e9ponses, ou bien vous vous demandez comment combler les <strong data-start=\"617\" data-end=\"636\">lacunes de votre<\/strong> CV. Quel que soit le d\u00e9fi, nos <strong data-start=\"694\" data-end=\"720\">conseillers en emploi<\/strong> exp\u00e9riment\u00e9s sont pr\u00eats \u00e0 vous aider ! Ils peuvent vous fournir les informations et les strat\u00e9gies dont vous avez besoin pour faire bonne impression et d\u00e9crocher votre prochaine opportunit\u00e9.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Comment fonctionnent nos s\u00e9ances d&rsquo;information gratuites<\/strong><\/h2>\n<p>Nos consultations de 15 minutes vous donnent un acc\u00e8s direct \u00e0 un conseiller en emploi exp\u00e9riment\u00e9. Ils peuvent r\u00e9pondre \u00e0 vos questions urgentes et vous proposer des solutions pratiques. Si vous n&rsquo;avez pas encore de conseiller en mati\u00e8re d&#8217;emploi ou si vous avez besoin d&rsquo;une aide de derni\u00e8re minute pour votre recherche d&#8217;emploi, c&rsquo;est l&rsquo;occasion id\u00e9ale d&rsquo;obtenir des conseils professionnels.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Ce pour quoi vous pouvez obtenir de l&rsquo;aide<\/strong><\/h2>\n<p>\ud83d\udd39 Examens de CV et de lettres de motivation &#8211; Apprenez \u00e0 adapter votre candidature pour qu&rsquo;elle se d\u00e9marque.<br \/>\n\ud83d\udd39 Optimisation du profil LinkedIn &#8211; Faites en sorte que votre profil soit pr\u00eat pour l&#8217;employeur.<br \/>\n\ud83d\udd39 Pr\u00e9paration aux entretiens &#8211; Obtenez des conseils pour r\u00e9pondre aux questions difficiles en toute confiance.<br \/>\n\ud83d\udd39 Combler les lacunes en mati\u00e8re d&#8217;emploi &#8211; Apprenez \u00e0 positionner efficacement les interruptions de carri\u00e8re.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>R\u00e9servez votre s\u00e9ance gratuite d\u00e8s aujourd&rsquo;hui !<\/strong><\/h2>\n<p>Profitez de ce soutien gratuit \u00e0 la recherche d&#8217;emploi et b\u00e9n\u00e9ficiez de l&rsquo;aide d&rsquo;un expert lorsque vous en avez besoin. Ne manquez pas cette occasion d&rsquo;avancer dans votre carri\u00e8re. R\u00e9servez d\u00e8s aujourd&rsquo;hui votre s\u00e9ance d&rsquo;information gratuite pour les demandeurs d&#8217;emploi !<\/p>\n<p data-start=\"681\" data-end=\"780\">\ud83d\udcc5 <strong data-start=\"684\" data-end=\"713\">Disponible du lundi au jeudi<\/strong><br data-start=\"713\" data-end=\"716\" \/>\u23f0 <strong data-start=\"718\" data-end=\"740\">12:00 &#8211; 13:00<\/strong><br data-start=\"740\" data-end=\"743\" \/>\ud83d\udccd <strong data-start=\"746\" data-end=\"778\">Inscription pr\u00e9alable requise<\/strong><\/p>\n<p data-start=\"782\" data-end=\"855\">\ud83d\udca1 <strong data-start=\"785\" data-end=\"799\">Important :<\/strong> Ces sessions sont ouvertes <strong data-start=\"827\" data-end=\"853\">uniquement<\/strong> aux <strong data-start=\"827\" data-end=\"853\">r\u00e9sidents du Qu\u00e9bec.<\/strong><\/p>\n<p data-start=\"857\" data-end=\"943\"><strong data-start=\"857\" data-end=\"905\">Les places sont limit\u00e9es et la r\u00e9servation est obligatoire.<\/strong><\/p>\n<p>Pour plus d&rsquo;informations ou pour r\u00e9server votre place, <strong><a href=\"mailto:info@yesmontreal.ca\" target=\"_blank\" rel=\"noopener\">nous envoyer un courriel<\/a><\/strong>.<\/p>\n<p>Pour en savoir plus sur nos services de l&#8217;emploi, cliquez <strong><a href=\"https:\/\/yesmontreal.ca\/employment\/\" target=\"_blank\" rel=\"noopener\">ici<\/a><\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Obtenez des conseils d&rsquo;experts en recherche d&#8217;emploi sur votre CV, votre lettre de motivation, LinkedIn et les entretiens gr\u00e2ce \u00e0 nos sessions gratuites pour les demandeurs d&#8217;emploi.  <\/p>\n","protected":false},"author":10,"featured_media":0,"template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[321,267,346,326,347,83,343,320,345],"tribe_events_cat":[281,344,284],"class_list":["post-85348","tribe_events","type-tribe_events","status-publish","hentry","tag-carriere","tag-cv","tag-cv-fr","tag-developpement-de-carriere","tag-entretien-dembauche","tag-job-seeker","tag-job-seeker-fr","tag-lemploi","tag-lettre-de-motivation","tribe_events_cat-daytime-fr","tribe_events_cat-employment-fr","tribe_events_cat-virtual-fr","cat_daytime-fr","cat_employment-fr","cat_virtual-fr","tribe-recurring-event","tribe-recurring-event-child"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Obtenir des conseils d&#039;experts en mati\u00e8re de recherche d&#039;emploi - S\u00e9ances d&#039;information pour les demandeurs d&#039;emploi<\/title>\n<meta name=\"description\" content=\"Obtenez des conseils d&#039;experts en recherche d&#039;emploi sur votre CV, votre lettre de motivation, LinkedIn et les entretiens gr\u00e2ce \u00e0 nos sessions gratuites pour les demandeurs d&#039;emploi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/yesmontreal.ca\/fr\/event\/seances-dinformation-pour-les-demandeurs-demploi\/2025-05-22\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Obtenir des conseils d&#039;experts en mati\u00e8re de recherche d&#039;emploi - S\u00e9ances d&#039;information pour les demandeurs d&#039;emploi\" \/>\n<meta property=\"og:description\" content=\"Obtenez des conseils d&#039;experts en recherche d&#039;emploi sur votre CV, votre lettre de motivation, LinkedIn et les entretiens gr\u00e2ce \u00e0 nos sessions gratuites pour les demandeurs d&#039;emploi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/yesmontreal.ca\/fr\/event\/seances-dinformation-pour-les-demandeurs-demploi\/2025-05-22\/\" \/>\n<meta property=\"og:site_name\" content=\"YES Employment and Entrepreneurship\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/yes.montreal\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-16T20:11:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/yesmontreal.ca\/wp-content\/uploads\/job-interview.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@YESMontreal\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/yesmontreal.ca\\\/fr\\\/event\\\/seances-dinformation-pour-les-demandeurs-demploi\\\/2025-05-22\\\/\",\"url\":\"https:\\\/\\\/yesmontreal.ca\\\/fr\\\/event\\\/seances-dinformation-pour-les-demandeurs-demploi\\\/2025-05-22\\\/\",\"name\":\"Obtenir des conseils d'experts en mati\u00e8re de recherche d'emploi - S\u00e9ances d'information pour les demandeurs d'emploi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/yesmontreal.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/yesmontreal.ca\\\/fr\\\/event\\\/seances-dinformation-pour-les-demandeurs-demploi\\\/2025-05-22\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/yesmontreal.ca\\\/fr\\\/event\\\/seances-dinformation-pour-les-demandeurs-demploi\\\/2025-05-22\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/yesmontreal.ca\\\/wp-content\\\/uploads\\\/job-interview.jpg\",\"datePublished\":\"2025-05-16T19:26:24+00:00\",\"dateModified\":\"2025-05-16T20:11:08+00:00\",\"description\":\"Obtenez des conseils d'experts en recherche d'emploi sur votre CV, votre lettre de motivation, LinkedIn et les entretiens gr\u00e2ce \u00e0 nos sessions gratuites pour les demandeurs d'emploi.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/yesmontreal.ca\\\/fr\\\/event\\\/seances-dinformation-pour-les-demandeurs-demploi\\\/2025-05-22\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/yesmontreal.ca\\\/fr\\\/event\\\/seances-dinformation-pour-les-demandeurs-demploi\\\/2025-05-22\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/yesmontreal.ca\\\/fr\\\/event\\\/seances-dinformation-pour-les-demandeurs-demploi\\\/2025-05-22\\\/#primaryimage\",\"url\":\"https:\\\/\\\/yesmontreal.ca\\\/wp-content\\\/uploads\\\/job-interview.jpg\",\"contentUrl\":\"https:\\\/\\\/yesmontreal.ca\\\/wp-content\\\/uploads\\\/job-interview.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/yesmontreal.ca\\\/fr\\\/event\\\/seances-dinformation-pour-les-demandeurs-demploi\\\/2025-05-22\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/yesmontreal.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/yesmontreal.ca\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"S\u00e9ances d&#8217;information pour les demandeurs d&#8217;emploi\",\"item\":\"https:\\\/\\\/yesmontreal.ca\\\/fr\\\/event\\\/seances-dinformation-pour-les-demandeurs-demploi\\\/2025-03-24\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"S\u00e9ances d&#8217;information pour les demandeurs d&#8217;emploi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/yesmontreal.ca\\\/#website\",\"url\":\"https:\\\/\\\/yesmontreal.ca\\\/\",\"name\":\"YES Employment and Entrepreneurship\",\"description\":\"Free Employment and Entrepreneurship services in Quebec\",\"publisher\":{\"@id\":\"https:\\\/\\\/yesmontreal.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/yesmontreal.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/yesmontreal.ca\\\/#organization\",\"name\":\"YES Employment + Entrepreneurship\",\"alternateName\":\"YES Montreal\",\"url\":\"https:\\\/\\\/yesmontreal.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/yesmontreal.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/yesmontreal.ca\\\/wp-content\\\/uploads\\\/Screen-Shot-2021-03-04-at-2.59.30-PM.png\",\"contentUrl\":\"https:\\\/\\\/yesmontreal.ca\\\/wp-content\\\/uploads\\\/Screen-Shot-2021-03-04-at-2.59.30-PM.png\",\"width\":636,\"height\":308,\"caption\":\"YES Employment + Entrepreneurship\"},\"image\":{\"@id\":\"https:\\\/\\\/yesmontreal.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/yes.montreal\",\"https:\\\/\\\/x.com\\\/YESMontreal\",\"https:\\\/\\\/www.instagram.com\\\/yesmontreal\\\/\",\"http:\\\/\\\/ca.linkedin.com\\\/in\\\/yesmontreal\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/YESMontreal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Obtenir des conseils d'experts en mati\u00e8re de recherche d'emploi - S\u00e9ances d'information pour les demandeurs d'emploi","description":"Obtenez des conseils d'experts en recherche d'emploi sur votre CV, votre lettre de motivation, LinkedIn et les entretiens gr\u00e2ce \u00e0 nos sessions gratuites pour les demandeurs d'emploi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/yesmontreal.ca\/fr\/event\/seances-dinformation-pour-les-demandeurs-demploi\/2025-05-22\/","og_locale":"fr_FR","og_type":"article","og_title":"Obtenir des conseils d'experts en mati\u00e8re de recherche d'emploi - S\u00e9ances d'information pour les demandeurs d'emploi","og_description":"Obtenez des conseils d'experts en recherche d'emploi sur votre CV, votre lettre de motivation, LinkedIn et les entretiens gr\u00e2ce \u00e0 nos sessions gratuites pour les demandeurs d'emploi.","og_url":"https:\/\/yesmontreal.ca\/fr\/event\/seances-dinformation-pour-les-demandeurs-demploi\/2025-05-22\/","og_site_name":"YES Employment and Entrepreneurship","article_publisher":"https:\/\/www.facebook.com\/yes.montreal","article_modified_time":"2025-05-16T20:11:08+00:00","og_image":[{"width":940,"height":627,"url":"https:\/\/yesmontreal.ca\/wp-content\/uploads\/job-interview.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@YESMontreal","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/yesmontreal.ca\/fr\/event\/seances-dinformation-pour-les-demandeurs-demploi\/2025-05-22\/","url":"https:\/\/yesmontreal.ca\/fr\/event\/seances-dinformation-pour-les-demandeurs-demploi\/2025-05-22\/","name":"Obtenir des conseils d'experts en mati\u00e8re de recherche d'emploi - S\u00e9ances d'information pour les demandeurs d'emploi","isPartOf":{"@id":"https:\/\/yesmontreal.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/yesmontreal.ca\/fr\/event\/seances-dinformation-pour-les-demandeurs-demploi\/2025-05-22\/#primaryimage"},"image":{"@id":"https:\/\/yesmontreal.ca\/fr\/event\/seances-dinformation-pour-les-demandeurs-demploi\/2025-05-22\/#primaryimage"},"thumbnailUrl":"https:\/\/yesmontreal.ca\/wp-content\/uploads\/job-interview.jpg","datePublished":"2025-05-16T19:26:24+00:00","dateModified":"2025-05-16T20:11:08+00:00","description":"Obtenez des conseils d'experts en recherche d'emploi sur votre CV, votre lettre de motivation, LinkedIn et les entretiens gr\u00e2ce \u00e0 nos sessions gratuites pour les demandeurs d'emploi.","breadcrumb":{"@id":"https:\/\/yesmontreal.ca\/fr\/event\/seances-dinformation-pour-les-demandeurs-demploi\/2025-05-22\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/yesmontreal.ca\/fr\/event\/seances-dinformation-pour-les-demandeurs-demploi\/2025-05-22\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/yesmontreal.ca\/fr\/event\/seances-dinformation-pour-les-demandeurs-demploi\/2025-05-22\/#primaryimage","url":"https:\/\/yesmontreal.ca\/wp-content\/uploads\/job-interview.jpg","contentUrl":"https:\/\/yesmontreal.ca\/wp-content\/uploads\/job-interview.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/yesmontreal.ca\/fr\/event\/seances-dinformation-pour-les-demandeurs-demploi\/2025-05-22\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/yesmontreal.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/yesmontreal.ca\/events\/"},{"@type":"ListItem","position":3,"name":"S\u00e9ances d&#8217;information pour les demandeurs d&#8217;emploi","item":"https:\/\/yesmontreal.ca\/fr\/event\/seances-dinformation-pour-les-demandeurs-demploi\/2025-03-24\/"},{"@type":"ListItem","position":4,"name":"S\u00e9ances d&#8217;information pour les demandeurs d&#8217;emploi"}]},{"@type":"WebSite","@id":"https:\/\/yesmontreal.ca\/#website","url":"https:\/\/yesmontreal.ca\/","name":"YES Employment and Entrepreneurship","description":"Free Employment and Entrepreneurship services in Quebec","publisher":{"@id":"https:\/\/yesmontreal.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/yesmontreal.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/yesmontreal.ca\/#organization","name":"YES Employment + Entrepreneurship","alternateName":"YES Montreal","url":"https:\/\/yesmontreal.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/yesmontreal.ca\/#\/schema\/logo\/image\/","url":"https:\/\/yesmontreal.ca\/wp-content\/uploads\/Screen-Shot-2021-03-04-at-2.59.30-PM.png","contentUrl":"https:\/\/yesmontreal.ca\/wp-content\/uploads\/Screen-Shot-2021-03-04-at-2.59.30-PM.png","width":636,"height":308,"caption":"YES Employment + Entrepreneurship"},"image":{"@id":"https:\/\/yesmontreal.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/yes.montreal","https:\/\/x.com\/YESMontreal","https:\/\/www.instagram.com\/yesmontreal\/","http:\/\/ca.linkedin.com\/in\/yesmontreal","https:\/\/www.youtube.com\/user\/YESMontreal"]}]}},"_links":{"self":[{"href":"https:\/\/yesmontreal.ca\/fr\/wp-json\/wp\/v2\/tribe_events\/85348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yesmontreal.ca\/fr\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/yesmontreal.ca\/fr\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/yesmontreal.ca\/fr\/wp-json\/wp\/v2\/users\/10"}],"version-history":[{"count":0,"href":"https:\/\/yesmontreal.ca\/fr\/wp-json\/wp\/v2\/tribe_events\/85348\/revisions"}],"wp:attachment":[{"href":"https:\/\/yesmontreal.ca\/fr\/wp-json\/wp\/v2\/media?parent=85348"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/yesmontreal.ca\/fr\/wp-json\/wp\/v2\/tags?post=85348"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/yesmontreal.ca\/fr\/wp-json\/wp\/v2\/tribe_events_cat?post=85348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}